{"id":35529,"date":"2024-08-21T16:55:55","date_gmt":"2024-08-21T14:55:55","guid":{"rendered":"https:\/\/rosagres.com\/leticia-lopez-pereira-balneario-de-lanjaron\/"},"modified":"2025-02-18T15:27:32","modified_gmt":"2025-02-18T14:27:32","slug":"leticia-lopez-pereira-balneario-de-lanjaron","status":"publish","type":"page","link":"https:\/\/rosagres.com\/fr\/architecture\/leticia-lopez-pereira-balneario-de-lanjaron\/","title":{"rendered":"LETICIA L\u00d3PEZ PEREIRA \u2013 Balneario de Lanjar\u00f3n"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<style>.thegem-te-post-breadcrumbs.thegem-custom-6a97b5a5b06523717 .post-breadcrumbs {justify-content: left; text-align: left;}.thegem-te-post-breadcrumbs.thegem-custom-6a97b5a5b06523717 .post-breadcrumbs ul {justify-content: left; text-align: left;}<\/style><div class=\"thegem-te-post-breadcrumbs thegem-custom-6a97b5a5b06523717\"> <div class=\"post-breadcrumbs\"><ul><li><a href=\"https:\/\/rosagres.com\/fr\/\">Accueil<\/a><\/li><\/ul><!-- .breadcrumbs --><\/div> <\/div>[\/vc_column][\/vc_row][vc_row equal_height=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1724245113031{margin-bottom: 0px !important;}\u00a0\u00bb el_class=\u00a0\u00bbno-gutter\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1724242878225{padding-top: 30px !important;padding-bottom: 50px !important;background-color: #f8f8f8 !important;}\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1724251618230{padding-top: 10px !important;padding-right: 40px !important;padding-bottom: 10px !important;padding-left: 40px !important;}\u00a0\u00bb]<\/p>\n<h2><a href=\"https:\/\/www.balneariodelanjaron.es\/\" target=\"_blank\" rel=\"noopener\">BALNEARIO DE LANJAR\u00d3N<\/a><br \/>\nLANJAR\u00d3N<br \/>\nGRANADA, ESPAGNE<\/h2>\n<p>ARCHITECTE<br \/>\n<strong>LETICIA L\u00d3PEZ PEREIRA<\/strong><\/p>\n<p>PROJET<br \/>\n<strong>PISCINE ZONES INT\u00c9RIEURES \u2013 ESPACE SPA<\/strong><\/p>\n<p>COLORIS ROSA GRES<br \/>\n<strong>TAO BEIGE \u2013 BASSIN DE LA PISCINE<\/strong><br \/>\n<strong>ALMA FOREST \u2013 BORD DE LA PISCINE<\/strong><br \/>\n<strong>TAO BROWN \u2013 ZONE \u00c9L\u00c9V\u00c9E<\/strong>[\/vc_column_text][vc_empty_space height=\u00a0\u00bb12px\u00a0\u00bb el_class=\u00a0\u00bbmobile\u00a0\u00bb][vc_single_image image=\u00a0\u00bb35499&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbmobile\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1739818532572{background-image: url(https:\/\/rosagres.com\/wp-content\/uploads\/2025\/02\/rosa-gres-arquitectura-balneario-lanjaron-leticia-lopez-pereira-.webp?id=35497) !important;}\u00a0\u00bb offset=\u00a0\u00bbvc_hidden-sm vc_hidden-xs\u00a0\u00bb][\/vc_column][\/vc_row][vc_row equal_height=\u00a0\u00bbyes\u00a0\u00bb content_placement=\u00a0\u00bbtop\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1724245042443{margin-bottom: 0px !important;}\u00a0\u00bb el_class=\u00a0\u00bbno-gutter\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1724242933729{padding-top: 15px !important;background-color: #f1eee9 !important;}\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bb\u201c\u2026l\u2019avenir d\u00e9pendra de l\u2019architecture du pass\u00e9 C\u2019est donc s\u00fbrement le moment id\u00e9al de se recr\u00e9er en revenant aux anciennes formes de construction.\u201d\u00a0\u00bb font_container=\u00a0\u00bbtag:p|font_size:48px|text_align:left|color:%2376a6b4|line_height:55px\u00a0\u00bb google_fonts=\u00a0\u00bbfont_family:Alice%3Aregular|font_style:400%20regular%3A400%3Anormal\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1724251656067{padding-top: 10px !important;padding-right: 40px !important;padding-bottom: 10px !important;padding-left: 40px !important;}\u00a0\u00bb el_class=\u00a0\u00bbfuente-arquitectura arquitectura-medio-2 azul\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1724242963342{background-color: #666666 !important;}\u00a0\u00bb el_class=\u00a0\u00bbbg-top-left\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1724251679279{padding-top: 15px !important;padding-right: 40px !important;padding-bottom: 40px !important;padding-left: 40px !important;}\u00a0\u00bb]<\/p>\n<h3>\u00c0 QUOI RESSEMBLERA L\u2019ARCHITECTURE DANS UN SI\u00c8CLE ?<\/h3>\n<p>Ce sera une architecture qui retournera \u00e0 ses racines, une architecture durable, \u00e9cologique et verte, o\u00f9 l\u2019\u00eatre humain cessera d\u2019\u00eatre le centre de l\u2019univers (\u2026) On tendra \u00e0 revenir \u00e0 des constructions plus traditionnelles, mais qui resteront technologiques bien s\u00fbr, car nous ne pouvons pas revenir en arri\u00e8re et ne pr\u00e9tendons pas le faire. Par contre, oui, nous allons revenir \u00e0 des constructions beaucoup plus durables, plus vertes et plus \u00e9cologiques.<\/p>\n<h3>QUEL EST LE PROJET DE VOS R\u00caVES ?<\/h3>\n<p>Tout projet dans lequel la majorit\u00e9 des d\u00e9cisions ne serait pas influenc\u00e9e par des questions \u00e9conomiques. Tout projet auquel je travaillerais sans rel\u00e2che, de fa\u00e7on obsessionnelle, et qui serait source de joie malgr\u00e9 les difficult\u00e9s.<\/p>\n<h3>POUR VOUS, QU\u2019EST-CE QUE L\u2019 ME D\u2019UN PROJET ?<\/h3>\n<p>C\u2019est une question un peu insolite et je vais vous dire pourquoi\u2026 Qu\u2019entendez-vous par le terme d\u2019\u00e2me ? L\u2019id\u00e9e ? L\u2019origine de l\u2019id\u00e9e ? Les efforts et les soins que vous consacrez \u00e0 cr\u00e9er votre projet ? Le d\u00e9sir ? L\u2019\u00e9motion de cr\u00e9er quelque chose de nouveau ? Un projet peut avoir une \u00e2me ou plusieurs \u00e2mes. Peut-\u00eatre que chaque projet a une \u00e2me diff\u00e9rente, et que tout d\u00e9pend de chaque projet et de chaque moment. C\u2019est une question \u00e0 laquelle il est n\u00e9cessaire de r\u00e9fl\u00e9chir pour chaque projet. Je ne pense pas que l\u2019on puisse r\u00e9pondre de fa\u00e7on g\u00e9n\u00e9ralis\u00e9e pour tous les projets.<\/p>\n<h3>QUE CHANGERIEZ-VOUS DANS LE SECTEUR DU B TIMENT ?<\/h3>\n<p>Les mauvaises habitudes, de toute \u00e9vidence. Le \u00ab on a toujours fait comme \u00e7a \u00bb que l\u2019on vous oppose, alors que les choses ont toujours \u00e9t\u00e9 mal faites d\u00e8s le d\u00e9but. Le manque d\u2019organisation, le manque de dialogue entre les diff\u00e9rents corps de m\u00e9tier. C\u2019est vraiment une grande lacune. On a tendance \u00e0 cr\u00e9er des corps de m\u00e9tier compl\u00e8tement cloisonn\u00e9s, alors qu\u2019ils devraient \u00eatre perm\u00e9ables et fluides et qu\u2019il faudrait cr\u00e9er des relations presque mim\u00e9tiques entre eux pour que pouvoir mener \u00e0 bien les projets, avec facilit\u00e9 et simplicit\u00e9.<\/p>\n<h3>QU\u2019EST-CE QUE VOUS NE CHANGERIEZ JAMAIS ?<\/h3>\n<p>Je ne changerais jamais les mod\u00e8les traditionnels efficaces et solidement \u00e9tablis. Nous devrions y revenir continuellement, pour les r\u00e9inventer, les \u00e9tudier et s\u2019en servir de source d\u2019inspiration. Comme je viens de le dire, l\u2019avenir d\u00e9pendra de l\u2019architecture du pass\u00e9. C\u2019est donc s\u00fbrement le moment id\u00e9al de se recr\u00e9er en revenant aux anciennes formes de construction.<br \/>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00a0\u00bb.vc_custom_1724249899351{margin-bottom: 0px !important;padding-right: 0px !important;padding-left: 0px !important;}\u00a0\u00bb][vc_column css=\u00a0\u00bb.vc_custom_1724249892146{padding-right: 0px !important;padding-left: 0px !important;}\u00a0\u00bb][vc_single_image image=\u00a0\u00bb35502&Prime; img_size=\u00a0\u00bb1183&#215;790&Prime; css=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbaumenta-1180&Prime;][\/vc_column][\/vc_row][vc_row equal_height=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1724245919115{margin-bottom: 0px !important;}\u00a0\u00bb el_class=\u00a0\u00bbno-gutter\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1724245770568{padding-top: 25px !important;padding-bottom: 50px !important;}\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb22px\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1724251720395{padding-right: 40px !important;padding-bottom: 10px !important;padding-left: 40px !important;}\u00a0\u00bb]<\/p>\n<h3 class=\"azul\">CONCERNANT LE CONCEPT CR\u00c9ATIF DE CE PROJET, DONNEZ-NOUS UNE D\u00c9FINITION DE SON STYLE.<br \/>\nUNA DEFINICI\u00d3N DE ESTILO.<\/h3>\n<p class=\"texto-\">Ce projet d\u00e9marre sur des pr\u00e9misses un peu diff\u00e9rentes de celles que l\u2019on voit habituellement. La pr\u00e9misse de d\u00e9part est un espace ferm\u00e9, qui a une histoire, dans lequel nous devions inclure un \u00e9l\u00e9ment technologique, r\u00e9pondant \u00e0 un objectif de loisir.<\/p>\n<p class=\"texto-\">Le concept est n\u00e9 des crit\u00e8res impos\u00e9s par le client et du besoin d\u2019espace, mais aussi de la n\u00e9cessit\u00e9 de pr\u00e9server l\u2019histoire de l\u2019\u00e9difice. Il est construit en briques brutes apparentes et ses formes suivent les traces sp\u00e9cifiques \u00e0 l\u2019architecture historiciste n\u00e9o-mud\u00e9jar du d\u00e9but du si\u00e8cle.<\/p>\n<p>[\/vc_column_text][vc_empty_space height=\u00a0\u00bb12px\u00a0\u00bb el_class=\u00a0\u00bbmobile\u00a0\u00bb][vc_single_image image=\u00a0\u00bb35505&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1739818660293{padding-bottom: 0px !important;}\u00a0\u00bb el_class=\u00a0\u00bbmobile\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime; background_position_desktop=\u00a0\u00bbcenter bottom\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1739818654392{background-image: url(https:\/\/rosagres.com\/wp-content\/uploads\/2025\/02\/rosa-gres-arquitectura-balneario-lanjaron-02.webp?id=35503) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}\u00a0\u00bb offset=\u00a0\u00bbvc_hidden-sm vc_hidden-xs\u00a0\u00bb][\/vc_column][\/vc_row][vc_row equal_height=\u00a0\u00bbyes\u00a0\u00bb el_class=\u00a0\u00bbno-gutter\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1724245892314{margin-bottom: 0px !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; background_position_desktop=\u00a0\u00bbcenter bottom\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1739818733075{background-image: url(https:\/\/rosagres.com\/wp-content\/uploads\/2025\/02\/rosa-gres-arquitectura-balneario-lanjaron-07.webp?id=35518) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}\u00a0\u00bb offset=\u00a0\u00bbvc_hidden-sm vc_hidden-xs\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1724244681035{padding-top: 25px !important;padding-bottom: 50px !important;}\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb22px\u00a0\u00bb el_class=\u00a0\u00bbno-mobile\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1724251758659{padding-right: 40px !important;padding-bottom: 10px !important;padding-left: 40px !important;}\u00a0\u00bb el_class=\u00a0\u00bbno-gutter\u00a0\u00bb]<\/p>\n<h4>Quel \u00e9tait l\u2019\u00e9l\u00e9ment le plus important et que repr\u00e9sentait cet espace ?<\/h4>\n<p class=\"texto-\">Sans aucun doute les sources, qui sont le c\u0153ur du Balneario. Il s\u2019agit des sources chaudes, dont la temp\u00e9rature est d\u2019environ 25\u00ba C \u00e0\u00a0<strong>El Salado<\/strong>, et qui sont riches en chlorhydrates de sodium et en mangan\u00e8se. Et d\u2019autre part, les sources d\u2019eau froide, d\u2019une temp\u00e9rature de 16\u00ba C pour celle de San Vicente, ce sont des eaux acides, alcalines et ferrugineuses, qui jaillissent de sols \u00e9rod\u00e9s de talcschiste et d\u2019argile schisteux. Et sans oublier en toile de fond, l\u2019escalier, et aussi les grandes fen\u00eatres et cet espace imposant qui est domin\u00e9 par des colonnades.<\/p>\n<p>[\/vc_column_text][vc_empty_space height=\u00a0\u00bb12px\u00a0\u00bb el_class=\u00a0\u00bbmobile\u00a0\u00bb][vc_single_image image=\u00a0\u00bb35520&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbmobile\u00a0\u00bb][\/vc_column][\/vc_row][vc_row equal_height=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1724245919115{margin-bottom: 0px !important;}\u00a0\u00bb el_class=\u00a0\u00bbno-gutter\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1724245770568{padding-top: 25px !important;padding-bottom: 50px !important;}\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb22px\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1724251807855{padding-right: 40px !important;padding-bottom: 10px !important;padding-left: 40px !important;}\u00a0\u00bb]<\/p>\n<p class=\"texto-\">Nous nous sommes efforc\u00e9s de pr\u00e9server tout ce qui fait partie de l\u2019histoire de l\u2019\u00e9difice et de l\u2019histoire de Lanjar\u00f3n, de le conserver, de le mettre en valeur et de l\u2019am\u00e9nager de fa\u00e7on pratique et utile pour le nouvel usage auquel \u00e9tait destin\u00e9 cet espace. Le client nous a communiqu\u00e9 un ensemble de crit\u00e8res minimaux \u00e0 respecter en vue de ce nouvel usage. Les installations n\u00e9cessaires pour assurer ce service \u00e9taient tr\u00e8s complexes et sont tr\u00e8s encombrantes.<\/p>\n<p class=\"texto-\">Nous pensons avoir r\u00e9ussi \u00e0 conserver l\u2019idiosyncrasie du lieu, \u00e0 la renforcer et en m\u00eame temps, \u00e0 cr\u00e9er un nouvel usage pour cet espace et \u00e0 le faire entrer dans le XXIe si\u00e8cle sans lui donner un aspect trop technologique, trop froid et futuriste. Apr\u00e8s tout, les clients se rendent dans un spa parce qu\u2019ils veulent se d\u00e9tendre et se retrouver dans un environnement agr\u00e9able.<\/p>\n<p class=\"texto-\">Nous pensons avoir atteint notre but gr\u00e2ce aux mat\u00e9riaux, \u00e0 la gamme de couleurs choisie, \u00e0 la lumi\u00e8re que nous avons fait entrer, aux vues qu\u2019offrent les grandes fen\u00eatres, \u00e0 l\u2019\u00e9nergie du lieu lui-m\u00eame.<\/p>\n<p>[\/vc_column_text][vc_empty_space height=\u00a0\u00bb12px\u00a0\u00bb el_class=\u00a0\u00bbmobile\u00a0\u00bb][vc_single_image image=\u00a0\u00bb35511&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1739818759922{padding-bottom: 0px !important;}\u00a0\u00bb el_class=\u00a0\u00bbmobile\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime; background_position_desktop=\u00a0\u00bbcenter bottom\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1739818753301{background-image: url(https:\/\/rosagres.com\/wp-content\/uploads\/2025\/02\/rosa-gres-arquitectura-balneario-lanjaron-03.webp?id=35509) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}\u00a0\u00bb offset=\u00a0\u00bbvc_hidden-sm vc_hidden-xs\u00a0\u00bb][\/vc_column][\/vc_row][vc_row css=\u00a0\u00bb.vc_custom_1724245069071{margin-bottom: 0px !important;background-color: #f8f8f8 !important;}\u00a0\u00bb el_class=\u00a0\u00bbno-gutter\u00a0\u00bb][vc_column][vc_custom_heading text=\u00a0\u00bb\u00ab\u2026 l\u2019environnement \u00e9tait un espace vide, et notre contrainte \u00e9tait un vaste \u00e9crin architectural avec de beaux panoramas.\u00bb\u00a0\u00bb font_container=\u00a0\u00bbtag:p|font_size:38px|text_align:center|color:%235b6e74|line_height:45px\u00a0\u00bb google_fonts=\u00a0\u00bbfont_family:Alice%3Aregular|font_style:400%20regular%3A400%3Anormal\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1724251858272{padding-top: 10px !important;padding-right: 40px !important;padding-bottom: 10px !important;padding-left: 40px !important;}\u00a0\u00bb el_class=\u00a0\u00bbfuente-arquitectura arquitectura-medio-2 azul\u00a0\u00bb][\/vc_column][\/vc_row][vc_row equal_height=\u00a0\u00bbyes\u00a0\u00bb el_class=\u00a0\u00bbno-gutter\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1724245892314{margin-bottom: 0px !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; background_position_desktop=\u00a0\u00bbcenter bottom\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1739818775871{background-image: url(https:\/\/rosagres.com\/wp-content\/uploads\/2025\/02\/rosa-gres-arquitectura-balneario-lanjaron-04.webp?id=35512) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}\u00a0\u00bb offset=\u00a0\u00bbvc_hidden-sm vc_hidden-xs\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1724244681035{padding-top: 25px !important;padding-bottom: 50px !important;}\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb22px\u00a0\u00bb el_class=\u00a0\u00bbno-mobile\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1724251899482{padding-right: 40px !important;padding-bottom: 10px !important;padding-left: 40px !important;}\u00a0\u00bb el_class=\u00a0\u00bbno-gutter\u00a0\u00bb]<\/p>\n<h3 class=\"azul\">PAYSAGE, ENVIRONNEMENT ET CONCEPTION, COMMENT S\u2019INT\u00c8GRENT-ILS ?<\/h3>\n<p class=\"texto-\">De fa\u00e7on g\u00e9n\u00e9rale, la conception est obligatoirement conditionn\u00e9e par l\u2019environnement, la topographie, la pr\u00e9sence d\u2019arbres, le lit d\u2019une rivi\u00e8re. Ce sont des \u00e9l\u00e9ments qui doivent \u00eatre pris en compte lors de l\u2019\u00e9laboration du projet.<\/p>\n<p class=\"texto-\">L\u2019environnement est un facteur plus contraignant que les panoramas \u00e0 l\u2019heure d\u2019imaginer et de concevoir un projet.<\/p>\n<p class=\"texto-\">Dans notre cas, l\u2019environnement \u00e9tait un espace vide, et notre contrainte \u00e9tait un vaste \u00e9crin architectural avec de beaux panoramas. Nous devions pr\u00e9server ces deux qualit\u00e9s, l\u2019h\u00e9ritage historique et les vues panoramiques. Nous nous y sommes conform\u00e9s avec t\u00e9nacit\u00e9 jusqu\u2019\u00e0 obtenir une distribution optimale des espaces et \u00e0 souligner tous les \u00e9l\u00e9ments que nous souhaitions mettre en valeur, en essayant de les int\u00e9grer le mieux possible \u00e0 la conception finale du projet.<\/p>\n<p>[\/vc_column_text][vc_empty_space height=\u00a0\u00bb12px\u00a0\u00bb el_class=\u00a0\u00bbmobile\u00a0\u00bb][vc_single_image image=\u00a0\u00bb35514&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbmobile\u00a0\u00bb][\/vc_column][\/vc_row][vc_row css=\u00a0\u00bb.vc_custom_1724245069071{margin-bottom: 0px !important;background-color: #f8f8f8 !important;}\u00a0\u00bb el_class=\u00a0\u00bbno-gutter\u00a0\u00bb][vc_column][vc_custom_heading text=\u00a0\u00bb\u00abAu cours du processus de cr\u00e9ation, j\u2019ai une vision du projet dans une couleur pr\u00e9cise et, m\u00eame si j\u2019\u00e9tudie d\u2019autres possibilit\u00e9s, je finis par me rendre compte que cette premi\u00e8re intuition est la bonne.\u00bb\u00a0\u00bb font_container=\u00a0\u00bbtag:p|font_size:38px|text_align:center|color:%235b6e74|line_height:45px\u00a0\u00bb google_fonts=\u00a0\u00bbfont_family:Alice%3Aregular|font_style:400%20regular%3A400%3Anormal\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1724251918480{padding-top: 10px !important;padding-right: 40px !important;padding-bottom: 10px !important;padding-left: 40px !important;}\u00a0\u00bb el_class=\u00a0\u00bbfuente-arquitectura arquitectura-medio-2 azul\u00a0\u00bb][\/vc_column][\/vc_row][vc_row equal_height=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1724245919115{margin-bottom: 0px !important;}\u00a0\u00bb el_class=\u00a0\u00bbno-gutter\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1724245770568{padding-top: 25px !important;padding-bottom: 50px !important;}\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb22px\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1724251935725{padding-right: 40px !important;padding-bottom: 10px !important;padding-left: 40px !important;}\u00a0\u00bb]<\/p>\n<h3 class=\"azul\">COMMENT CHOISISSEZ-VOUS LES COLORIS ?<\/h3>\n<p>Mes choix reposent certainement sur mes go\u00fbts personnels ou sur un penchant qui m\u2019est propre. Je tends toujours vers le gris, le blanc et le noir, c\u2019est ce qui m\u2019attire naturellement, mais en fin de compte, je crois que chaque projet exige de vous quelque chose de diff\u00e9rent, et c\u2019est le cas de ce projet.<\/p>\n<p>Au cours du processus de cr\u00e9ation, j\u2019ai une vision du projet dans une couleur pr\u00e9cise et, m\u00eame si j\u2019\u00e9tudie d\u2019autres possibilit\u00e9s, je finis par me rendre compte que cette premi\u00e8re intuition est la bonne. Est-ce que \u00e7a veut dire que ma d\u00e9cision est presque toujours correcte ou qu\u2019au moins dans mon cas, elle se base sur une raison scientifique ? La r\u00e9ponse est non, s\u00fbrement pas. Mes choix sont conditionn\u00e9s par des go\u00fbts, par des modes, par beaucoup d\u2019autres \u00e9l\u00e9ments externes, mais en d\u00e9finitive c\u2019est tout cet ensemble de facteurs qui doit s\u2019exprimer.<br \/>\n[\/vc_column_text][vc_empty_space height=\u00a0\u00bb12px\u00a0\u00bb el_class=\u00a0\u00bbmobile\u00a0\u00bb][vc_single_image image=\u00a0\u00bb35517&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1739818809698{padding-bottom: 0px !important;}\u00a0\u00bb el_class=\u00a0\u00bbmobile\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime; background_position_desktop=\u00a0\u00bbcenter bottom\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1739818804038{background-image: url(https:\/\/rosagres.com\/wp-content\/uploads\/2025\/02\/rosa-gres-arquitectura-balneario-lanjaron-05.webp?id=35515) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}\u00a0\u00bb offset=\u00a0\u00bbvc_hidden-sm vc_hidden-xs\u00a0\u00bb][\/vc_column][\/vc_row][vc_row equal_height=\u00a0\u00bbyes\u00a0\u00bb el_class=\u00a0\u00bbno-gutter\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1724245892314{margin-bottom: 0px !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; background_position_desktop=\u00a0\u00bbcenter bottom\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1739818833439{background-image: url(https:\/\/rosagres.com\/wp-content\/uploads\/2025\/02\/rosa-gres-arquitectura-balneario-lanjaron-06.webp?id=35506) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}\u00a0\u00bb offset=\u00a0\u00bbvc_hidden-sm vc_hidden-xs\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1725400427114{padding-top: 25px !important;padding-bottom: 50px !important;}\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb22px\u00a0\u00bb el_class=\u00a0\u00bbno-mobile\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1725400266677{padding-right: 40px !important;padding-bottom: 10px !important;padding-left: 40px !important;}\u00a0\u00bb el_class=\u00a0\u00bbno-gutter\u00a0\u00bb]<\/p>\n<h3 class=\"azul\">\u00c0 QUELS D\u00c9FIS AVEZ-VOUS \u00c9T\u00c9 CONFRONT\u00c9E AU COURS DE CE PROJET ?<\/h3>\n<p>Pour moi, le grand d\u00e9fi pos\u00e9 par ce projet a \u00e9t\u00e9 de surmonter les contraintes sentimentales et \u00e9motionnelles envers un lieu que je connaissais et appr\u00e9ciais depuis toujours, d\u2019une fa\u00e7on \u00e0 laquelle je m\u2019\u00e9tais habitu\u00e9e, et auquel je devais faire subir une transformation fondamentale.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"azul\">QUELS SONT LES D\u00c9FIS POS\u00c9S PAR LA CONCEPTION D\u2019UNE PISCINE THERMALE ?<\/h3>\n<p class=\"texto-\">On ne peut pas g\u00e9n\u00e9raliser car chaque projet particulier implique une solution qui lui est propre. Pour r\u00e9sumer en termes g\u00e9n\u00e9raux, j\u2019essaie d\u2019imaginer des constructions qui s\u2019adaptent \u00e0 la topographie existante, afin de cr\u00e9er une interaction entre l\u2019architecture et le paysage. L\u2019id\u00e9e est que l\u2019architecture elle-m\u00eame paraisse \u00eatre en lien avec le paysage, comme si elle en \u00e9tait une extension.<\/p>\n<p>Je m\u2019efforce d\u2019\u00eatre respectueuse de l\u2019environnement en termes d\u2019\u00e9chelles et de mat\u00e9riaux, mais en m\u00eame temps, je vais vouloir tenter une piscine en harmonie avec notre \u00e9poque, le tout au sein d\u2019un volume qui a \u00e9t\u00e9 fa\u00e7onn\u00e9 par la topographie.<br \/>\n[\/vc_column_text][vc_empty_space height=\u00a0\u00bb12px\u00a0\u00bb el_class=\u00a0\u00bbmobile\u00a0\u00bb][vc_single_image image=\u00a0\u00bb35508&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbmobile\u00a0\u00bb][\/vc_column][\/vc_row][vc_row equal_height=\u00a0\u00bbyes\u00a0\u00bb content_placement=\u00a0\u00bbtop\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1724245042443{margin-bottom: 0px !important;}\u00a0\u00bb el_class=\u00a0\u00bbno-gutter\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1725400437684{padding-top: 25px !important;padding-bottom: 50px !important;}\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb12px\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1725400351507{padding-right: 40px !important;padding-bottom: 10px !important;padding-left: 40px !important;}\u00a0\u00bb el_class=\u00a0\u00bbno-gutter\u00a0\u00bb]<\/p>\n<h3 class=\"azul\">QUELS \u00c9L\u00c9MENTS ET CONCEPTS ARCHITECTURAUX AVEZ-VOUS PRIS EN COMPTE POUR RENFORCER LA DURABILIT\u00c9 DU PROJET ?<\/h3>\n<p>Pour ce projet particulier, l\u2019enjeu de la durabilit\u00e9 est plus restreint car il est conditionn\u00e9 par l\u2019existant. Mais nous avons veill\u00e9 \u00e0 utiliser des mat\u00e9riaux d\u2019origine nationale pour r\u00e9duire les transports. Nous avons optimis\u00e9 la lumi\u00e8re naturelle qui entre par les grandes fen\u00eatres, nous avons mis en valeur la richesse hydrique de la r\u00e9gion en cr\u00e9ant un bar \u00e0 eaux. Ce ne sont que de petites touches qui \u00e9voquent la norme qui devra pr\u00e9dominer demain.[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime; el_class=\u00a0\u00bbbg-top-left\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1725400369263{background-color: #f8f8f8 !important;}\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bb\u00ab\u2026 cr\u00e9er une interaction entre l\u2019architecture et le paysage. L\u2019id\u00e9e est que l\u2019architecture elle-m\u00eame paraisse \u00eatre en lien avec le paysage, comme si elle en \u00e9tait une extension.\u00bb\u00a0\u00bb font_container=\u00a0\u00bbtag:p|font_size:38px|text_align:left|color:%2376a6b4|line_height:45px\u00a0\u00bb google_fonts=\u00a0\u00bbfont_family:Alice%3Aregular|font_style:400%20regular%3A400%3Anormal\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1725400304270{padding-top: 10px !important;padding-right: 40px !important;padding-bottom: 10px !important;padding-left: 40px !important;}\u00a0\u00bb el_class=\u00a0\u00bbfuente-arquitectura arquitectura-medio-2 azul\u00a0\u00bb][\/vc_column][\/vc_row][vc_row css=\u00a0\u00bb.vc_custom_1725400735008{margin-bottom: 0px !important;padding-right: 0px !important;padding-left: 0px !important;}\u00a0\u00bb][vc_column css=\u00a0\u00bb.vc_custom_1724249892146{padding-right: 0px !important;padding-left: 0px !important;}\u00a0\u00bb][vc_single_image image=\u00a0\u00bb35523&Prime; img_size=\u00a0\u00bb1183&#215;790&Prime; css=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbaumenta-1180&Prime;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_row equal_height=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1724245113031{margin-bottom: 0px !important;}\u00a0\u00bb el_class=\u00a0\u00bbno-gutter\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1724242878225{padding-top: 30px !important;padding-bottom: 50px !important;background-color: #f8f8f8 !important;}\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1724251618230{padding-top: 10px !important;padding-right: 40px !important;padding-bottom: 10px&#8230;<\/p>\n","protected":false},"author":1,"featured_media":35499,"parent":35847,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-35529","page","type-page","status-publish","has-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/rosagres.com\/fr\/wp-json\/wp\/v2\/pages\/35529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rosagres.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rosagres.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rosagres.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rosagres.com\/fr\/wp-json\/wp\/v2\/comments?post=35529"}],"version-history":[{"count":0,"href":"https:\/\/rosagres.com\/fr\/wp-json\/wp\/v2\/pages\/35529\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rosagres.com\/fr\/wp-json\/wp\/v2\/pages\/35847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rosagres.com\/fr\/wp-json\/wp\/v2\/media\/35499"}],"wp:attachment":[{"href":"https:\/\/rosagres.com\/fr\/wp-json\/wp\/v2\/media?parent=35529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}